{"id":18468,"date":"2026-09-02T06:45:35","date_gmt":"2026-09-02T04:45:35","guid":{"rendered":"https:\/\/letrainjaune.fr\/a-voir-et-a-faire\/agenda\/marche-local-30-septembre\/"},"modified":"2026-09-02T06:45:35","modified_gmt":"2026-09-02T04:45:35","slug":"marche-local-30-septembre","status":"publish","type":"agenda","link":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/","title":{"rendered":"MARCH\u00c9 LOCAL &#8211; 30 SEPTEMBRE"},"content":{"rendered":"<p>Vente et d\u00e9gustation de produits de saison et de bien d\u2019autres petits plaisirs&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vente et d\u00e9gustation de produits de saison et de bien d\u2019autres petits plaisirs&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","agenda_category":[],"class_list":["post-18468","agenda","type-agenda","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MARCH\u00c9 LOCAL - 30 SEPTEMBRE - Dest\u00ed: El Tren Groc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MARCH\u00c9 LOCAL - 30 SEPTEMBRE - Dest\u00ed: El Tren Groc\" \/>\n<meta property=\"og:description\" content=\"Vente et d\u00e9gustation de produits de saison et de bien d\u2019autres petits plaisirs...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dest\u00ed: El Tren Groc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/agenda\\\/marche-local-30-septembre\\\/\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/agenda\\\/marche-local-30-septembre\\\/\",\"name\":\"MARCH\u00c9 LOCAL - 30 SEPTEMBRE - Dest\u00ed: El Tren Groc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#website\"},\"datePublished\":\"2026-09-02T04:45:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/agenda\\\/marche-local-30-septembre\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/agenda\\\/marche-local-30-septembre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/agenda\\\/marche-local-30-septembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Benvinguda\",\"item\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MARCH\u00c9 LOCAL &#8211; 30 SEPTEMBRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/\",\"name\":\"Dest\u00ed: El Tren Groc\",\"description\":\"Dans les Pyr\u00e9n\u00e9es Catalanes, d\u00e9couvrez ce train sur le plus haut chemin de fer d\u2019Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#organization\",\"name\":\"Dest\u00ed: El Tren Groc\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TJ_logo-TJ-footer.svg\",\"contentUrl\":\"https:\\\/\\\/letrainjaune.fr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TJ_logo-TJ-footer.svg\",\"width\":\"1920\",\"height\":\"9999\",\"caption\":\"Dest\u00ed: El Tren Groc\"},\"image\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MARCH\u00c9 LOCAL - 30 SEPTEMBRE - Dest\u00ed: El Tren Groc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/","og_locale":"ca_ES","og_type":"article","og_title":"MARCH\u00c9 LOCAL - 30 SEPTEMBRE - Dest\u00ed: El Tren Groc","og_description":"Vente et d\u00e9gustation de produits de saison et de bien d\u2019autres petits plaisirs...","og_url":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/","og_site_name":"Dest\u00ed: El Tren Groc","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/","url":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/","name":"MARCH\u00c9 LOCAL - 30 SEPTEMBRE - Dest\u00ed: El Tren Groc","isPartOf":{"@id":"https:\/\/letrainjaune.fr\/ca\/#website"},"datePublished":"2026-09-02T04:45:35+00:00","breadcrumb":{"@id":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/marche-local-30-septembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Benvinguda","item":"https:\/\/letrainjaune.fr\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/agenda\/"},{"@type":"ListItem","position":3,"name":"MARCH\u00c9 LOCAL &#8211; 30 SEPTEMBRE"}]},{"@type":"WebSite","@id":"https:\/\/letrainjaune.fr\/ca\/#website","url":"https:\/\/letrainjaune.fr\/ca\/","name":"Dest\u00ed: El Tren Groc","description":"Dans les Pyr\u00e9n\u00e9es Catalanes, d\u00e9couvrez ce train sur le plus haut chemin de fer d\u2019Europe.","publisher":{"@id":"https:\/\/letrainjaune.fr\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrainjaune.fr\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/letrainjaune.fr\/ca\/#organization","name":"Dest\u00ed: El Tren Groc","url":"https:\/\/letrainjaune.fr\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/letrainjaune.fr\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/letrainjaune.fr\/wp-content\/uploads\/2021\/04\/TJ_logo-TJ-footer.svg","contentUrl":"https:\/\/letrainjaune.fr\/wp-content\/uploads\/2021\/04\/TJ_logo-TJ-footer.svg","width":"1920","height":"9999","caption":"Dest\u00ed: El Tren Groc"},"image":{"@id":"https:\/\/letrainjaune.fr\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/agenda\/18468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/agenda"}],"about":[{"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/types\/agenda"}],"wp:attachment":[{"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/media?parent=18468"}],"wp:term":[{"taxonomy":"agenda_category","embeddable":true,"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/agenda_category?post=18468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}