{"id":17400,"date":"2026-03-18T05:45:29","date_gmt":"2026-03-18T04:45:29","guid":{"rendered":"https:\/\/letrainjaune.fr\/a-voir-et-a-faire\/activites-nature\/ozone-3-montagne-et-loisirs\/"},"modified":"2026-09-02T06:45:30","modified_gmt":"2026-09-02T04:45:30","slug":"ozone-3-montagne-et-loisirs","status":"publish","type":"nature","link":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/","title":{"rendered":"OZONE 3 &#8211; MONTAGNE ET LOISIRS"},"content":{"rendered":"<p>Accompagnateurs en montagne, moniteur de canyoning et d\u2019escalade, pilote de montgolfi\u00e8re\u2026 depuis 30 ans, le Bureau Montagne Ozone 3 et son \u00e9quipe sont heureux de vous accueillir tout au long de l&#8217;ann\u00e9e pour vous faire d\u00e9couvrir les merveilles de nos Pyr\u00e9n\u00e9es catalanes.<br \/>\nL&#8217;\u00e9quipe d&#8217;Ozone 3 vous accompagnera en\u00a0:<br \/>\n&#8211; Randonn\u00e9e \u00e9t\u00e9 \/ hiver (raquettes)<br \/>\n&#8211; Ski de fond et de randonn\u00e9e<br \/>\n&#8211; Accrobranche (d\u00e8s 3 ans), Via ferrata (d\u00e8s 5 ans)<br \/>\n&#8211; Rando \u00e9questre<br \/>\n&#8211; Chiens de tra\u00eeneaux<br \/>\n-Plong\u00e9e sous glace<br \/>\n&#8211; Quad VT<br \/>\n-Canyoning<br \/>\n-Canyon en eau chaude<br \/>\n-Fat bike<br \/>\n-VTT<br \/>\n-Montgolfi\u00e8re<br \/>\nEt plein autres activit\u00e9s \u00e0 venir d\u00e9couvrir\u00a0!<\/p>\n<p>Le Bureau Montagne Ozone 3 organise \u00e9galement votre s\u00e9minaire d\u2019entreprise \u00e0 travers ses challenges multi-activit\u00e9s.<\/p>\n<p>S\u00e9jours itin\u00e9rants en raquettes pour d\u00e9couvrir les Pyr\u00e9n\u00e9es Catalanes autrement.<br \/>\n Randonn\u00e9es \u00e9questres, escalade, sorties marmottes d\u00e8s 4 ans. . Canyon en eaux chaudes, p\u00eache, tir \u00e0 l\u2019arc, club des aventuriers d\u00e8s 6 ans. Randonn\u00e9e, rafting, montgolfi\u00e8re d\u00e8s 8 ans.<\/p>\n","protected":false},"featured_media":0,"template":"","nature_category":[47,38,37,43,35,44,41,42,32],"class_list":["post-17400","nature","type-nature","status-publish","hentry","nature_category-course-trail","nature_category-guides-randonnee","nature_category-guides-velo","nature_category-loisirs-hiver","nature_category-raquettes","nature_category-ski-de-fond-randonnee","nature_category-sports-aeriens","nature_category-sports-aquatiques","nature_category-sports-de-grimpe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OZONE 3 - MONTAGNE ET LOISIRS - Dest\u00ed: El Tren Groc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OZONE 3 - MONTAGNE ET LOISIRS - Dest\u00ed: El Tren Groc\" \/>\n<meta property=\"og:description\" content=\"Accompagnateurs en montagne, moniteur de canyoning et d\u2019escalade, pilote de montgolfi\u00e8re\u2026 depuis 30 ans, le Bureau Montagne Ozone 3 et son \u00e9quipe sont heureux de vous accueillir tout au long de l&#039;ann\u00e9e pour vous faire d\u00e9couvrir les merveilles de nos Pyr\u00e9n\u00e9es catalanes. L&#039;\u00e9quipe d&#039;Ozone 3 vous accompagnera en\u00a0: - Randonn\u00e9e \u00e9t\u00e9 \/ hiver (raquettes) - Ski de fond et de randonn\u00e9e - Accrobranche (d\u00e8s 3 ans), Via ferrata (d\u00e8s 5 ans) - Rando \u00e9questre - Chiens de tra\u00eeneaux -Plong\u00e9e sous glace - Quad VT -Canyoning -Canyon en eau chaude -Fat bike -VTT -Montgolfi\u00e8re Et plein autres activit\u00e9s \u00e0 venir d\u00e9couvrir\u00a0! Le Bureau Montagne Ozone 3 organise \u00e9galement votre s\u00e9minaire d\u2019entreprise \u00e0 travers ses challenges multi-activit\u00e9s. S\u00e9jours itin\u00e9rants en raquettes pour d\u00e9couvrir les Pyr\u00e9n\u00e9es Catalanes autrement.  Randonn\u00e9es \u00e9questres, escalade, sorties marmottes d\u00e8s 4 ans. . Canyon en eaux chaudes, p\u00eache, tir \u00e0 l\u2019arc, club des aventuriers d\u00e8s 6 ans. Randonn\u00e9e, rafting, montgolfi\u00e8re d\u00e8s 8 ans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/\" \/>\n<meta property=\"og:site_name\" content=\"Dest\u00ed: El Tren Groc\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T04:45:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/activitats-a-la-natura\\\/ozone-3-montagne-et-loisirs\\\/\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/activitats-a-la-natura\\\/ozone-3-montagne-et-loisirs\\\/\",\"name\":\"OZONE 3 - MONTAGNE ET LOISIRS - Dest\u00ed: El Tren Groc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#website\"},\"datePublished\":\"2026-03-18T04:45:29+00:00\",\"dateModified\":\"2026-09-02T04:45:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/activitats-a-la-natura\\\/ozone-3-montagne-et-loisirs\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/activitats-a-la-natura\\\/ozone-3-montagne-et-loisirs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/activitats-a-la-natura\\\/ozone-3-montagne-et-loisirs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Benvinguda\",\"item\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activitats a la natura\",\"item\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/per-veure-i-fer\\\/activitats-a-la-natura\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"OZONE 3 &#8211; MONTAGNE ET LOISIRS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/\",\"name\":\"Dest\u00ed: El Tren Groc\",\"description\":\"Dans les Pyr\u00e9n\u00e9es Catalanes, d\u00e9couvrez ce train sur le plus haut chemin de fer d\u2019Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#organization\",\"name\":\"Dest\u00ed: El Tren Groc\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TJ_logo-TJ-footer.svg\",\"contentUrl\":\"https:\\\/\\\/letrainjaune.fr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TJ_logo-TJ-footer.svg\",\"width\":\"1920\",\"height\":\"9999\",\"caption\":\"Dest\u00ed: El Tren Groc\"},\"image\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OZONE 3 - MONTAGNE ET LOISIRS - Dest\u00ed: El Tren Groc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/","og_locale":"ca_ES","og_type":"article","og_title":"OZONE 3 - MONTAGNE ET LOISIRS - Dest\u00ed: El Tren Groc","og_description":"Accompagnateurs en montagne, moniteur de canyoning et d\u2019escalade, pilote de montgolfi\u00e8re\u2026 depuis 30 ans, le Bureau Montagne Ozone 3 et son \u00e9quipe sont heureux de vous accueillir tout au long de l'ann\u00e9e pour vous faire d\u00e9couvrir les merveilles de nos Pyr\u00e9n\u00e9es catalanes. L'\u00e9quipe d'Ozone 3 vous accompagnera en\u00a0: - Randonn\u00e9e \u00e9t\u00e9 \/ hiver (raquettes) - Ski de fond et de randonn\u00e9e - Accrobranche (d\u00e8s 3 ans), Via ferrata (d\u00e8s 5 ans) - Rando \u00e9questre - Chiens de tra\u00eeneaux -Plong\u00e9e sous glace - Quad VT -Canyoning -Canyon en eau chaude -Fat bike -VTT -Montgolfi\u00e8re Et plein autres activit\u00e9s \u00e0 venir d\u00e9couvrir\u00a0! Le Bureau Montagne Ozone 3 organise \u00e9galement votre s\u00e9minaire d\u2019entreprise \u00e0 travers ses challenges multi-activit\u00e9s. S\u00e9jours itin\u00e9rants en raquettes pour d\u00e9couvrir les Pyr\u00e9n\u00e9es Catalanes autrement.  Randonn\u00e9es \u00e9questres, escalade, sorties marmottes d\u00e8s 4 ans. . Canyon en eaux chaudes, p\u00eache, tir \u00e0 l\u2019arc, club des aventuriers d\u00e8s 6 ans. Randonn\u00e9e, rafting, montgolfi\u00e8re d\u00e8s 8 ans.","og_url":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/","og_site_name":"Dest\u00ed: El Tren Groc","article_modified_time":"2026-09-02T04:45:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/","url":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/","name":"OZONE 3 - MONTAGNE ET LOISIRS - Dest\u00ed: El Tren Groc","isPartOf":{"@id":"https:\/\/letrainjaune.fr\/ca\/#website"},"datePublished":"2026-03-18T04:45:29+00:00","dateModified":"2026-09-02T04:45:30+00:00","breadcrumb":{"@id":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/ozone-3-montagne-et-loisirs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Benvinguda","item":"https:\/\/letrainjaune.fr\/ca\/"},{"@type":"ListItem","position":2,"name":"Activitats a la natura","item":"https:\/\/letrainjaune.fr\/ca\/per-veure-i-fer\/activitats-a-la-natura\/"},{"@type":"ListItem","position":3,"name":"OZONE 3 &#8211; MONTAGNE ET LOISIRS"}]},{"@type":"WebSite","@id":"https:\/\/letrainjaune.fr\/ca\/#website","url":"https:\/\/letrainjaune.fr\/ca\/","name":"Dest\u00ed: El Tren Groc","description":"Dans les Pyr\u00e9n\u00e9es Catalanes, d\u00e9couvrez ce train sur le plus haut chemin de fer d\u2019Europe.","publisher":{"@id":"https:\/\/letrainjaune.fr\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrainjaune.fr\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/letrainjaune.fr\/ca\/#organization","name":"Dest\u00ed: El Tren Groc","url":"https:\/\/letrainjaune.fr\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/letrainjaune.fr\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/letrainjaune.fr\/wp-content\/uploads\/2021\/04\/TJ_logo-TJ-footer.svg","contentUrl":"https:\/\/letrainjaune.fr\/wp-content\/uploads\/2021\/04\/TJ_logo-TJ-footer.svg","width":"1920","height":"9999","caption":"Dest\u00ed: El Tren Groc"},"image":{"@id":"https:\/\/letrainjaune.fr\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/nature\/17400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/nature"}],"about":[{"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/types\/nature"}],"wp:attachment":[{"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/media?parent=17400"}],"wp:term":[{"taxonomy":"nature_category","embeddable":true,"href":"https:\/\/letrainjaune.fr\/ca\/wp-json\/wp\/v2\/nature_category?post=17400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}