{"id":17584,"date":"2026-05-03T06:45:15","date_gmt":"2026-05-03T04:45:15","guid":{"rendered":"https:\/\/letrainjaune.fr\/a-voir-et-a-faire\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/"},"modified":"2026-09-02T06:45:33","modified_gmt":"2026-09-02T04:45:33","slug":"exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne","status":"publish","type":"agenda","link":"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/","title":{"rendered":"EXPOSITION 40 ANS DE COLLECTIONS &#8220;DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE&#8221;- MUS\u00c9E DE CERDAGNE"},"content":{"rendered":"<p>Exposition temporaire<br \/>\nDe la poussi\u00e8re \u00e0 la lumi\u00e8re : 40 ans de tr\u00e9sors cerdans<br \/>\n(9 mai 2026 &#8211; 31 octobre 2026)<br \/>\nBienvenue \u00e0 l&#8217;exposition anniversaire de la ferme Cal Mateu !<br \/>\nDepuis 40 ans, le Mus\u00e9e de Cerdagne \u0153uvre dans l\u2019ombre pour recueillir, prot\u00e9ger et \u00e9tudier les fragments de notre histoire commune. Aujourd&#8217;hui, nous sortons de nos r\u00e9serves des objets exceptionnels pour vous raconter une aventure unique : celle de la transformation du quotidien en patrimoine. Comment un objet du quotidien devient-il un tr\u00e9sor public ? Ce parcours immersif sous forme de sc\u00e9nettes invite les visiteurs \u00e0 suivre le cycle de vie des objets, de leur acquisition \u00e0 leur mise en valeur dans les vitrines.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exposition temporaire<br \/>\nDe la poussi\u00e8re \u00e0 la lumi\u00e8re : 40 ans de tr\u00e9sors cerdans<br \/>\n(9 mai 2026 &#8211; 31 octobre 2026)<br \/>\nBienvenue \u00e0 l&#8217;exposition anniversaire de la ferme Cal Mateu !<br \/>\nDepuis 40 ans, le Mus\u00e9e de Cerdagne \u0153uvre dans l\u2019ombre pour recueillir, prot\u00e9ger et \u00e9tudier les fragments de notre histoire commune. Aujourd&#8217;hui, nous sortons de nos r\u00e9serves des objets exceptionnels pour vous raconter une aventure unique : celle de la transformation du quotidien en patrimoine. Comment un objet du quotidien devient-il un tr\u00e9sor public ? Ce parcours immersif sous forme de sc\u00e9nettes invite les visiteurs \u00e0 suivre le cycle de vie des objets, de leur acquisition \u00e0 leur mise en valeur dans les vitrines.<\/p>\n","protected":false},"featured_media":0,"template":"","agenda_category":[78],"class_list":["post-17584","agenda","type-agenda","status-publish","hentry","agenda_category-expositions-visites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXPOSITION 40 ANS DE COLLECTIONS &quot;DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE&quot;- MUS\u00c9E DE CERDAGNE - Let\u2019s Get on the Yellow Train<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXPOSITION 40 ANS DE COLLECTIONS &quot;DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE&quot;- MUS\u00c9E DE CERDAGNE - Let\u2019s Get on the Yellow Train\" \/>\n<meta property=\"og:description\" content=\"Exposition temporaire De la poussi\u00e8re \u00e0 la lumi\u00e8re : 40 ans de tr\u00e9sors cerdans (9 mai 2026 - 31 octobre 2026) Bienvenue \u00e0 l&#039;exposition anniversaire de la ferme Cal Mateu ! Depuis 40 ans, le Mus\u00e9e de Cerdagne \u0153uvre dans l\u2019ombre pour recueillir, prot\u00e9ger et \u00e9tudier les fragments de notre histoire commune. Aujourd&#039;hui, nous sortons de nos r\u00e9serves des objets exceptionnels pour vous raconter une aventure unique : celle de la transformation du quotidien en patrimoine. Comment un objet du quotidien devient-il un tr\u00e9sor public ? Ce parcours immersif sous forme de sc\u00e9nettes invite les visiteurs \u00e0 suivre le cycle de vie des objets, de leur acquisition \u00e0 leur mise en valeur dans les vitrines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Let\u2019s Get on the Yellow Train\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T04:45:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/to-see-and-do\\\/agenda\\\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\\\/\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/to-see-and-do\\\/agenda\\\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\\\/\",\"name\":\"EXPOSITION 40 ANS DE COLLECTIONS \\\"DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE\\\"- MUS\u00c9E DE CERDAGNE - Let\u2019s Get on the Yellow Train\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/#website\"},\"datePublished\":\"2026-05-03T04:45:15+00:00\",\"dateModified\":\"2026-09-02T04:45:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/to-see-and-do\\\/agenda\\\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/to-see-and-do\\\/agenda\\\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/to-see-and-do\\\/agenda\\\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/to-see-and-do\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EXPOSITION 40 ANS DE COLLECTIONS \u00ab\u00a0DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE\u00a0\u00bb- MUS\u00c9E DE CERDAGNE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/\",\"name\":\"Let\u2019s Get on the Yellow Train\",\"description\":\"Dans les Pyr\u00e9n\u00e9es Catalanes, d\u00e9couvrez ce train sur le plus haut chemin de fer d\u2019Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/#organization\",\"name\":\"Let\u2019s Get on the Yellow Train\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TJ_logo-TJ-footer.svg\",\"contentUrl\":\"https:\\\/\\\/letrainjaune.fr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TJ_logo-TJ-footer.svg\",\"width\":\"1920\",\"height\":\"9999\",\"caption\":\"Let\u2019s Get on the Yellow Train\"},\"image\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXPOSITION 40 ANS DE COLLECTIONS \"DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE\"- MUS\u00c9E DE CERDAGNE - Let\u2019s Get on the Yellow Train","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/","og_locale":"en_US","og_type":"article","og_title":"EXPOSITION 40 ANS DE COLLECTIONS \"DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE\"- MUS\u00c9E DE CERDAGNE - Let\u2019s Get on the Yellow Train","og_description":"Exposition temporaire De la poussi\u00e8re \u00e0 la lumi\u00e8re : 40 ans de tr\u00e9sors cerdans (9 mai 2026 - 31 octobre 2026) Bienvenue \u00e0 l'exposition anniversaire de la ferme Cal Mateu ! Depuis 40 ans, le Mus\u00e9e de Cerdagne \u0153uvre dans l\u2019ombre pour recueillir, prot\u00e9ger et \u00e9tudier les fragments de notre histoire commune. Aujourd'hui, nous sortons de nos r\u00e9serves des objets exceptionnels pour vous raconter une aventure unique : celle de la transformation du quotidien en patrimoine. Comment un objet du quotidien devient-il un tr\u00e9sor public ? Ce parcours immersif sous forme de sc\u00e9nettes invite les visiteurs \u00e0 suivre le cycle de vie des objets, de leur acquisition \u00e0 leur mise en valeur dans les vitrines.","og_url":"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/","og_site_name":"Let\u2019s Get on the Yellow Train","article_modified_time":"2026-09-02T04:45:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/","url":"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/","name":"EXPOSITION 40 ANS DE COLLECTIONS \"DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE\"- MUS\u00c9E DE CERDAGNE - Let\u2019s Get on the Yellow Train","isPartOf":{"@id":"https:\/\/letrainjaune.fr\/en\/#website"},"datePublished":"2026-05-03T04:45:15+00:00","dateModified":"2026-09-02T04:45:33+00:00","breadcrumb":{"@id":"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/exposition-40-ans-de-collections-de-la-poussiere-a-la-lumiere-musee-de-cerdagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/letrainjaune.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/letrainjaune.fr\/en\/to-see-and-do\/agenda\/"},{"@type":"ListItem","position":3,"name":"EXPOSITION 40 ANS DE COLLECTIONS \u00ab\u00a0DE LA POUSSI\u00c8RE \u00c0 LA LUMI\u00c8RE\u00a0\u00bb- MUS\u00c9E DE CERDAGNE"}]},{"@type":"WebSite","@id":"https:\/\/letrainjaune.fr\/en\/#website","url":"https:\/\/letrainjaune.fr\/en\/","name":"Let\u2019s Get on the Yellow Train","description":"Dans les Pyr\u00e9n\u00e9es Catalanes, d\u00e9couvrez ce train sur le plus haut chemin de fer d\u2019Europe.","publisher":{"@id":"https:\/\/letrainjaune.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrainjaune.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/letrainjaune.fr\/en\/#organization","name":"Let\u2019s Get on the Yellow Train","url":"https:\/\/letrainjaune.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/letrainjaune.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/letrainjaune.fr\/wp-content\/uploads\/2021\/04\/TJ_logo-TJ-footer.svg","contentUrl":"https:\/\/letrainjaune.fr\/wp-content\/uploads\/2021\/04\/TJ_logo-TJ-footer.svg","width":"1920","height":"9999","caption":"Let\u2019s Get on the Yellow Train"},"image":{"@id":"https:\/\/letrainjaune.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrainjaune.fr\/en\/wp-json\/wp\/v2\/agenda\/17584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrainjaune.fr\/en\/wp-json\/wp\/v2\/agenda"}],"about":[{"href":"https:\/\/letrainjaune.fr\/en\/wp-json\/wp\/v2\/types\/agenda"}],"wp:attachment":[{"href":"https:\/\/letrainjaune.fr\/en\/wp-json\/wp\/v2\/media?parent=17584"}],"wp:term":[{"taxonomy":"agenda_category","embeddable":true,"href":"https:\/\/letrainjaune.fr\/en\/wp-json\/wp\/v2\/agenda_category?post=17584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}