{"id":18228,"date":"2026-07-13T06:46:00","date_gmt":"2026-07-13T04:46:00","guid":{"rendered":"https:\/\/letrainjaune.fr\/a-voir-et-a-faire\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/"},"modified":"2026-07-15T06:45:34","modified_gmt":"2026-07-15T04:45:34","slug":"cinema-osseja-les-parfaits-arnaques-en-famille","status":"publish","type":"agenda","link":"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/","title":{"rendered":"CIN\u00c9MA OSS\u00c9JA &#8211; LES PARFAIT(S) : ARNAQUES EN FAMILLE"},"content":{"rendered":"<p>1h34 &#8211; Les Parfait(s) : arnaques en famille : Com\u00e9die r\u00e9alis\u00e9e Ludovic Bernard avec Audrey Fleurot, Ramzy Bedia, Alan Cumming\u2026<br \/>\n Chez les Toussaint, du grand-p\u00e8re au petit dernier, l\u2019arnaque est un art qui rapporte. Poursuivis, ils doivent fuir. Seule option ? Emprunter l\u2019identit\u00e9 d\u2019une famille sans histoire &#8211; les Parfait &#8211; et se r\u00e9fugier&#8230;en \u00c9cosse. Entre des coll\u00e8gues trop curieux et une myst\u00e9rieuse voisine, leur double vie va rapidement se compliquer : les faux Parfait se retrouvent face au coup d\u2019une vie. Plans d\u00e9mentiels, d\u00e9guisements fous, gadgets \u00e9tonnants : pour r\u00e9ussir, notre famille pas comme les autres va devoir prouver qu\u2019elle est plus que parfaite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1h34 &#8211; Les Parfait(s) : arnaques en famille : Com\u00e9die r\u00e9alis\u00e9e Ludovic Bernard avec Audrey Fleurot, Ramzy Bedia, Alan Cumming\u2026<br \/>\n Chez les Toussaint, du grand-p\u00e8re au petit dernier, l\u2019arnaque est un art qui rapporte. Poursuivis, ils doivent fuir. Seule option ? Emprunter l\u2019identit\u00e9 d\u2019une famille sans histoire &#8211; les Parfait &#8211; et se r\u00e9fugier&#8230;en \u00c9cosse. Entre des coll\u00e8gues trop curieux et une myst\u00e9rieuse voisine, leur double vie va rapidement se compliquer : les faux Parfait se retrouvent face au coup d\u2019une vie. Plans d\u00e9mentiels, d\u00e9guisements fous, gadgets \u00e9tonnants : pour r\u00e9ussir, notre famille pas comme les autres va devoir prouver qu\u2019elle est plus que parfaite.<\/p>\n","protected":false},"featured_media":0,"template":"","agenda_category":[81],"class_list":["post-18228","agenda","type-agenda","status-publish","hentry","agenda_category-theatre-cinema"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIN\u00c9MA OSS\u00c9JA - LES PARFAIT(S) : ARNAQUES EN FAMILLE - Destino Tren amarillo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIN\u00c9MA OSS\u00c9JA - LES PARFAIT(S) : ARNAQUES EN FAMILLE - Destino Tren amarillo\" \/>\n<meta property=\"og:description\" content=\"1h34 - Les Parfait(s) : arnaques en famille : Com\u00e9die r\u00e9alis\u00e9e Ludovic Bernard avec Audrey Fleurot, Ramzy Bedia, Alan Cumming\u2026                                                                     Chez les Toussaint, du grand-p\u00e8re au petit dernier, l\u2019arnaque est un art qui rapporte. Poursuivis, ils doivent fuir. Seule option ? Emprunter l\u2019identit\u00e9 d\u2019une famille sans histoire - les Parfait - et se r\u00e9fugier...en \u00c9cosse. Entre des coll\u00e8gues trop curieux et une myst\u00e9rieuse voisine, leur double vie va rapidement se compliquer : les faux Parfait se retrouvent face au coup d\u2019une vie. Plans d\u00e9mentiels, d\u00e9guisements fous, gadgets \u00e9tonnants : pour r\u00e9ussir, notre famille pas comme les autres va devoir prouver qu\u2019elle est plus que parfaite.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/\" \/>\n<meta property=\"og:site_name\" content=\"Destino Tren amarillo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T04:45:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/para-ver-y-hacer\\\/agenda\\\/cinema-osseja-les-parfaits-arnaques-en-famille\\\/\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/para-ver-y-hacer\\\/agenda\\\/cinema-osseja-les-parfaits-arnaques-en-famille\\\/\",\"name\":\"CIN\u00c9MA OSS\u00c9JA - LES PARFAIT(S) : ARNAQUES EN FAMILLE - Destino Tren amarillo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/#website\"},\"datePublished\":\"2026-07-13T04:46:00+00:00\",\"dateModified\":\"2026-07-15T04:45:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/para-ver-y-hacer\\\/agenda\\\/cinema-osseja-les-parfaits-arnaques-en-famille\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/para-ver-y-hacer\\\/agenda\\\/cinema-osseja-les-parfaits-arnaques-en-famille\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/para-ver-y-hacer\\\/agenda\\\/cinema-osseja-les-parfaits-arnaques-en-famille\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/para-ver-y-hacer\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CIN\u00c9MA OSS\u00c9JA &#8211; LES PARFAIT(S) : ARNAQUES EN FAMILLE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/\",\"name\":\"Destino Tren amarillo\",\"description\":\"Dans les Pyr\u00e9n\u00e9es Catalanes, d\u00e9couvrez ce train sur le plus haut chemin de fer d\u2019Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/#organization\",\"name\":\"Destino Tren amarillo\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrainjaune.fr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TJ_logo-TJ-footer.svg\",\"contentUrl\":\"https:\\\/\\\/letrainjaune.fr\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/TJ_logo-TJ-footer.svg\",\"width\":\"1920\",\"height\":\"9999\",\"caption\":\"Destino Tren amarillo\"},\"image\":{\"@id\":\"https:\\\/\\\/letrainjaune.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIN\u00c9MA OSS\u00c9JA - LES PARFAIT(S) : ARNAQUES EN FAMILLE - Destino Tren amarillo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/","og_locale":"es_ES","og_type":"article","og_title":"CIN\u00c9MA OSS\u00c9JA - LES PARFAIT(S) : ARNAQUES EN FAMILLE - Destino Tren amarillo","og_description":"1h34 - Les Parfait(s) : arnaques en famille : Com\u00e9die r\u00e9alis\u00e9e Ludovic Bernard avec Audrey Fleurot, Ramzy Bedia, Alan Cumming\u2026                                                                     Chez les Toussaint, du grand-p\u00e8re au petit dernier, l\u2019arnaque est un art qui rapporte. Poursuivis, ils doivent fuir. Seule option ? Emprunter l\u2019identit\u00e9 d\u2019une famille sans histoire - les Parfait - et se r\u00e9fugier...en \u00c9cosse. Entre des coll\u00e8gues trop curieux et une myst\u00e9rieuse voisine, leur double vie va rapidement se compliquer : les faux Parfait se retrouvent face au coup d\u2019une vie. Plans d\u00e9mentiels, d\u00e9guisements fous, gadgets \u00e9tonnants : pour r\u00e9ussir, notre famille pas comme les autres va devoir prouver qu\u2019elle est plus que parfaite.","og_url":"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/","og_site_name":"Destino Tren amarillo","article_modified_time":"2026-07-15T04:45:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/","url":"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/","name":"CIN\u00c9MA OSS\u00c9JA - LES PARFAIT(S) : ARNAQUES EN FAMILLE - Destino Tren amarillo","isPartOf":{"@id":"https:\/\/letrainjaune.fr\/es\/#website"},"datePublished":"2026-07-13T04:46:00+00:00","dateModified":"2026-07-15T04:45:34+00:00","breadcrumb":{"@id":"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/cinema-osseja-les-parfaits-arnaques-en-famille\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/letrainjaune.fr\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/letrainjaune.fr\/es\/para-ver-y-hacer\/agenda\/"},{"@type":"ListItem","position":3,"name":"CIN\u00c9MA OSS\u00c9JA &#8211; LES PARFAIT(S) : ARNAQUES EN FAMILLE"}]},{"@type":"WebSite","@id":"https:\/\/letrainjaune.fr\/es\/#website","url":"https:\/\/letrainjaune.fr\/es\/","name":"Destino Tren amarillo","description":"Dans les Pyr\u00e9n\u00e9es Catalanes, d\u00e9couvrez ce train sur le plus haut chemin de fer d\u2019Europe.","publisher":{"@id":"https:\/\/letrainjaune.fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrainjaune.fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/letrainjaune.fr\/es\/#organization","name":"Destino Tren amarillo","url":"https:\/\/letrainjaune.fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrainjaune.fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/letrainjaune.fr\/wp-content\/uploads\/2021\/04\/TJ_logo-TJ-footer.svg","contentUrl":"https:\/\/letrainjaune.fr\/wp-content\/uploads\/2021\/04\/TJ_logo-TJ-footer.svg","width":"1920","height":"9999","caption":"Destino Tren amarillo"},"image":{"@id":"https:\/\/letrainjaune.fr\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrainjaune.fr\/es\/wp-json\/wp\/v2\/agenda\/18228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrainjaune.fr\/es\/wp-json\/wp\/v2\/agenda"}],"about":[{"href":"https:\/\/letrainjaune.fr\/es\/wp-json\/wp\/v2\/types\/agenda"}],"wp:attachment":[{"href":"https:\/\/letrainjaune.fr\/es\/wp-json\/wp\/v2\/media?parent=18228"}],"wp:term":[{"taxonomy":"agenda_category","embeddable":true,"href":"https:\/\/letrainjaune.fr\/es\/wp-json\/wp\/v2\/agenda_category?post=18228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}